{"id":351,"date":"2024-07-12T23:02:36","date_gmt":"2024-07-12T23:02:36","guid":{"rendered":"https:\/\/sais3d.com\/?p=351"},"modified":"2024-07-15T05:33:01","modified_gmt":"2024-07-15T05:33:01","slug":"filamentos-pla-abs-asa-y-mas-en-impresion-3d","status":"publish","type":"post","link":"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/","title":{"rendered":"Filamentos PLA, ABS, ASA y m\u00e1s en impresi\u00f3n 3D"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"351\" class=\"elementor elementor-351\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-782c4a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"782c4a5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87b24b3\" data-id=\"87b24b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75a7f6c elementor-widget elementor-widget-text-editor\" data-id=\"75a7f6c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Las impresoras 3D permiten dise\u00f1ar y crear piezas \u00fanicas e innovadoras. Estas son muy \u00fatiles en \u00e1reas t\u00e9cnicas como son la ingenier\u00eda, la medicina y las ciencias, tambi\u00e9n se destaca su uso en \u00e1reas m\u00e1s comerciales como son el arte, el marketing y las ventas. Como es de esperar, se necesita que la pieza tenga las caracter\u00edsticas apropiadas para satisfacer los diversos requerimientos, en consecuencia es importante conocer que las cualidades del filamento que utilizamos sean las m\u00e1s convenientes para nuestros prop\u00f3sitos y el modo en que debemos utilizarlo. Pues bien, en este art\u00edculo te explicaremos algunos interesantes detalles sobre los filamentos PLA, ABS, ASA, policarbonato y m\u00e1s que se utilizan en las impresoras 3D.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e363c8 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1e363c8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7aeb7d83\" data-id=\"7aeb7d83\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dacfdf4 elementor-widget elementor-widget-image\" data-id=\"dacfdf4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/06\/osman-talha-dikyar-1MZ9JjAXg1E-unsplash-scaled.jpg\" class=\"attachment-full size-full wp-image-355\" alt=\"Filamento amarillo enrollado en un carrete.\" srcset=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/06\/osman-talha-dikyar-1MZ9JjAXg1E-unsplash-scaled.jpg 2560w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/06\/osman-talha-dikyar-1MZ9JjAXg1E-unsplash-768x512.jpg 768w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/06\/osman-talha-dikyar-1MZ9JjAXg1E-unsplash-1536x1024.jpg 1536w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/06\/osman-talha-dikyar-1MZ9JjAXg1E-unsplash-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Filamento para impresi\u00f3n 3D. Foto de <a href=\"https:\/\/unsplash.com\/es\/@osmantalha?utm_content=creditCopyText&amp;utm_medium=referral&amp;utm_source=unsplash\">Osman Talha Dikyar<\/a> en <a href=\"https:\/\/unsplash.com\/es\/fotos\/un-carrete-de-alambre-amarillo-sentado-encima-de-una-maquina-1MZ9JjAXg1E?utm_content=creditCopyText&amp;utm_medium=referral&amp;utm_source=unsplash\">Unsplash<\/a>\n  <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5d8047f4\" data-id=\"5d8047f4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52875b91 elementor-widget elementor-widget-heading\" data-id=\"52875b91\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h4 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 son los filamentos en impresi\u00f3n 3D?<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70897845 elementor-widget elementor-widget-text-editor\" data-id=\"70897845\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Los <a href=\"https:\/\/www.tme.com\/mx\/es\/news\/library-articles\/page\/51976\/filamentos-para-impresion-3d-tipos-caracteristicas-y-uso-en-prototipado\/\" target=\"_blank\" rel=\"noopener\">filamentos<\/a> son fibras delgadas y largas que sirven para imprimir objetos 3D. Estas vienen enrolladas en carretes que guardan varias docenas o incluso cientos de metros de largo. Los carretes son asegurados en los laterales de la impresora 3D para un buen funcionamiento durante la impresi\u00f3n.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9aa63de elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9aa63de\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-465883a\" data-id=\"465883a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b1e082 elementor-widget elementor-widget-heading\" data-id=\"2b1e082\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Filamentos como el PLA, ABS y ASA han ganado gran inter\u00e9s para ser utilizados en la industria de la impresi\u00f3n 3D<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1bcabf4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1bcabf4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e5b4da\" data-id=\"4e5b4da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-374ca34 elementor-widget elementor-widget-text-editor\" data-id=\"374ca34\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"MsoNormal\">Aunque existen diferentes tipos de filamentos, estos se caracterizan por estar conformados de <a href=\"https:\/\/polaridad.es\/que-son-los-termoplasticos\/#:~:text=Los%20termopl%C3%A1sticos%20son%20un%20tipo%20de%20pol%C3%ADmeros%20que,estado%20f%C3%ADsico%20cuando%20son%20sometidos%20a%20temperaturas%20elevadas.\" target=\"_blank\" rel=\"noopener\">materiales termopl\u00e1sticos<\/a>\u00a0por lo que tienen la capacidad de moldearse en funci\u00f3n del calor y la presi\u00f3n aplicados. As\u00ed, la impresora fuerza el filamento a trav\u00e9s de una boquilla caliente por esta raz\u00f3n la temperatura debe ser la indicada para fundir el filamento y colocarlo sobre una cama caliente. Por otro lado, la boquilla controla la salida del filamento de acuerdo a las instrucciones indicadas por el software de la impresora 3D. Entonces la calidad del resultado depende de la temperatura de extrusi\u00f3n del filamento y de la cama caliente de la impresora 3D. A continuaci\u00f3n te cuento algunas de las caracter\u00edsticas m\u00e1s importantes sobre filamentos como el PLA, ABS, ASA, policarbonato y m\u00e1s.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d6fd7d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d6fd7d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f2c59bd\" data-id=\"f2c59bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4209f5 elementor-widget elementor-widget-image\" data-id=\"e4209f5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1587\" height=\"1117\" src=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-PLA.png\" class=\"attachment-large size-large wp-image-602\" alt=\"Imagen de las aplicaciones del PLA.\" srcset=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-PLA.png 1587w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-PLA-768x541.png 768w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-PLA-1536x1081.png 1536w\" sizes=\"(max-width: 1587px) 100vw, 1587px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Aplicaciones del filamento PLA en juguetes, modelos y decoraciones.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ce1910c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce1910c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce09f93\" data-id=\"ce09f93\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5526862 elementor-widget elementor-widget-heading\" data-id=\"5526862\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1. Filamento PLA (\u00c1cido Polil\u00e1ctico)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7960e54 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7960e54\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a49d9fe\" data-id=\"a49d9fe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5873d0 elementor-widget elementor-widget-text-editor\" data-id=\"a5873d0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tEste filamento es ampliamente utilizado en la industria 3D debido su accesibilidad y a la facilidad para su manipulaci\u00f3n. Adem\u00e1s, su origen en recursos org\u00e1nicos y renovables lo vuelven uno de los termopl\u00e1sticos m\u00e1s sostenibles. Sin embargo, hay que tener en cuenta que su capacidad de biodegradaci\u00f3n depende de las condiciones de descomposici\u00f3n a las que se someta.\n<br>\n<br>\nEstas creaciones suelen ser fr\u00e1giles, y sensibles al sol y altas temperaturas. \u00a0Por tanto, es mayormente usado por principiantes para crear elementos decorativos, gadgets, y juguetes. Dentro del sector industrial, este material ayuda con la creaci\u00f3n de prototipos a un bajo coste de producci\u00f3n. Por \u00faltimo, aunque es menos frecuente el sector automotriz lo usa para crear adornos finales o para los salpicaderos de los carros. Aprende m\u00e1s sobre el filamento PLA en <a href=\"https:\/\/www.3dnatives.com\/es\/guia-filamento-pla-en-la-impresion-3d-190820192\/#!\" target=\"_blank\" rel=\"noopener\">Gu\u00eda&nbsp;Completa: El&nbsp;filamento&nbsp;de&nbsp;PLA&nbsp;en&nbsp;la&nbsp;impresi\u00f3n&nbsp;3D<\/a> de la revista virtual 3Dnatives.\n<br>\n<br>\nSe recomienda que durante la impresi\u00f3n el filamento se trabaje entre 190 y 220&nbsp;&deg;C pero esto depende del extrusor de la impresora 3D. Debido a la fragilidad del material se aconseja no realizar trabajos mec\u00e1nicos una vez impreso el dise\u00f1o. Adem\u00e1s, el modelo se volver\u00e1 endeble si se deja a temperaturas en torno a los 60 y 70&nbsp;&deg;C. Por otro lado, su origen org\u00e1nico, basado en ma\u00edz, produce un olor agradable y no t\u00f3xico para la salud. Lee sobre estas y m\u00e1s caracter\u00edsticas en\u00a0<a href=\"https:\/\/www.impresoras3d.com\/filamento-pla-consejos-caracteristicas-y-mucho-mas\/#Usos_del_filamento_PLA\" target=\"_blank\" rel=\"noopener\">Gu\u00eda&nbsp;de&nbsp;Uso: Filamento&nbsp;PLA&nbsp;para&nbsp;impresora&nbsp;3D<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0ee94b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0ee94b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-186bf05\" data-id=\"186bf05\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0f8164 elementor-widget elementor-widget-heading\" data-id=\"c0f8164\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Par\u00e1metros de Impresi\u00f3n:<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0887880\" data-id=\"0887880\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d08502 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5d08502\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/sais3d.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Temperatura boquilla:  190 - 220 \u00baC<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Temperatura plataforma:  60 - 70 \u00baC<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Distancia de retroacci\u00f3n: 0.4 - 1.2 mm<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Altura de capa: 0.2 - 0.21 mm<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-112adfa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"112adfa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c447d68\" data-id=\"c447d68\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5afead elementor-widget elementor-widget-image\" data-id=\"d5afead\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1740\" src=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/06\/kenny-eliason-kImlSU8Hc9c-unsplash-scaled.jpg\" class=\"attachment-large size-large wp-image-518\" alt=\"Impresora 3D sellada\" srcset=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/06\/kenny-eliason-kImlSU8Hc9c-unsplash-scaled.jpg 2560w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/06\/kenny-eliason-kImlSU8Hc9c-unsplash-768x522.jpg 768w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/06\/kenny-eliason-kImlSU8Hc9c-unsplash-1536x1044.jpg 1536w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/06\/kenny-eliason-kImlSU8Hc9c-unsplash-2048x1392.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Impresora 3D sellada para mantener la temperatura y contener gases nocivos. Foto de <a href=\"https:\/\/unsplash.com\/es\/@neonbrand?utm_content=creditCopyText&amp;utm_medium=referral&amp;utm_source=unsplash\">Kenny Eliason<\/a> en <a href=\"https:\/\/unsplash.com\/es\/fotos\/impresora-3d-en-negro-y-gris-kImlSU8Hc9c?utm_content=creditCopyText&amp;utm_medium=referral&amp;utm_source=unsplash\">Unsplash<\/a>\n  <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-adea983 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"adea983\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62edfb3\" data-id=\"62edfb3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a21d047 elementor-widget elementor-widget-heading\" data-id=\"a21d047\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2. Filamento ABS (Acrilonitrilo Butadieno Estireno)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a953fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a953fe\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-367582f\" data-id=\"367582f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4142fd elementor-widget elementor-widget-text-editor\" data-id=\"a4142fd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tSe caracteriza por crear piezas ligeras, tener una alta resistencia al impacto, a bajas temperaturas, al calor y a los qu\u00edmicos. Adem\u00e1s, cuenta con propiedades de aislamiento el\u00e9ctrico por lo que se utiliza para fabricar carcasas de componentes el\u00e9ctricos. Se produce utilizando el petr\u00f3leo como materia prima. Esto ha llevado a cuestionar su compromiso medioambiental. Sin embargo, se considera reciclable y es aceptado por algunos centros de reciclaje.\n<br>\n<br>\nEl filamento ABS es considerado como un material m\u00e1s t\u00e9cnico. Por lo que se utiliza en el sector industrial para crear prototipos, engranajes e incluso herramientas. Tambi\u00e9n, tiene aplicaciones en el sector de electrodom\u00e9sticos, en los cascos de barcos, en piezas de decoraci\u00f3n y juguetes.\n<br>\n<br>\nCuando se utiliza el ABS se aconseja mantener la temperatura de extrusi\u00f3n entre los 230 y 260&nbsp;&deg;C. Adem\u00e1s, es necesario que la bandeja de impresi\u00f3n se precaliente entre los 80 y 130&nbsp;&deg;C. As\u00ed se evita la contracci\u00f3n del material y el desprendimiento de la placa. Es importante recordar que este proceso se realice en un recinto cerrado. Esto ayuda a controlar la temperatura del material y evita respirar las part\u00edculas nocivas del pl\u00e1stico ABS. Conoce m\u00e1s detalles de este material en <a href=\"https:\/\/www.3dnatives.com\/es\/filamento-de-abs-impresion-3d-06062019\/#!\" target=\"_blank\" rel=\"noopener\">Gu\u00eda&nbsp;completa:\u00a0El&nbsp;filamento&nbsp;de&nbsp;ABS&nbsp;en&nbsp;la&nbsp;impresi\u00f3n&nbsp;3D<\/a>.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c753c32 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c753c32\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4255ab6\" data-id=\"4255ab6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b48b385 elementor-widget elementor-widget-heading\" data-id=\"b48b385\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Par\u00e1metros de Impresi\u00f3n:<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-99beb76\" data-id=\"99beb76\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33b9bf8 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"33b9bf8\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Temperatura boquilla: 230 - 260 \u00baC<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Temperatura plataforma: 80 - 130 \u00baC<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Distancia de retroacci\u00f3n: 5 - 6 mm<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Altura m\u00ednima de capa: 0.1 mm<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-178650f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"178650f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a10d13a\" data-id=\"a10d13a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfb0c55 elementor-widget elementor-widget-image\" data-id=\"bfb0c55\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/06\/jonathan-chng-OTDyDgPoJ_0-unsplash-scaled.jpg\" class=\"attachment-large size-large wp-image-519\" alt=\"Botellas pl\u00e1sticas hechas de PET\" srcset=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/06\/jonathan-chng-OTDyDgPoJ_0-unsplash-scaled.jpg 2560w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/06\/jonathan-chng-OTDyDgPoJ_0-unsplash-768x512.jpg 768w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/06\/jonathan-chng-OTDyDgPoJ_0-unsplash-1536x1024.jpg 1536w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/06\/jonathan-chng-OTDyDgPoJ_0-unsplash-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Botellas pl\u00e1sticas fabricadas con PET. Foto de <a href=\"https:\/\/unsplash.com\/es\/@jon_chng?utm_content=creditCopyText&amp;utm_medium=referral&amp;utm_source=unsplash\">Jonathan Chng<\/a> en <a href=\"https:\/\/unsplash.com\/es\/fotos\/lote-de-botellas-de-plastico-blanco-OTDyDgPoJ_0?utm_content=creditCopyText&amp;utm_medium=referral&amp;utm_source=unsplash\">Unsplash<\/a>\n  <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-468a74e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"468a74e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a1353d9\" data-id=\"a1353d9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3cff2b elementor-widget elementor-widget-heading\" data-id=\"f3cff2b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3. Filamento PETG (Tereftalato de Polietileno Glycol-modificado)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cedae76 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cedae76\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a054c0\" data-id=\"6a054c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c57de77 elementor-widget elementor-widget-text-editor\" data-id=\"c57de77\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tEs una variante del pol\u00edmero PET dise\u00f1ado para impresi\u00f3n 3D. El PET se usa com\u00fanmente para fabricar botellas, envases para alimentaci\u00f3n, fibras textiles, etc. El PETG es una f\u00f3rmula mejorada que lo hace m\u00e1s transparente, menos fr\u00e1gil y m\u00e1s f\u00e1cil de procesar.\n<br>\n<br>\nUna caracter\u00edstica destacable de este material es que cuenta con aprobaci\u00f3n de la FDA. Esto lo hace ideal para utilizarlo en el sector alimentario. Sin embargo, es necesario almacenarlo en un ambiente controlado y sin contaminantes. Tambi\u00e9n, tiene buena resistencia qu\u00edmica, no produce olor al imprimirse y se puede reciclar en conjunto con los envases y botellas pl\u00e1sticas.\n<br>\n<br>\nEn este material se debe mantener una temperatura de extrusi\u00f3n entre los 220 y 250&nbsp;&deg;C. Adem\u00e1s, la cama caliente se debe mantener a una temperatura entre los 60 y 90&nbsp;&deg;C. El PETG puede utilizarse en impresoras abiertas ya que no emite gases nocivos. Es recomendable utilizar un ventilador de capa para obtener una mejor calidad en las piezas. Revisa el blog <a href=\"https:\/\/bitfab.io\/es\/blog\/petg-impresion-3d\/\" target=\"_blank\" rel=\"noopener\">Todo&nbsp;sobre&nbsp;el&nbsp;PETG&nbsp;en&nbsp;impresi\u00f3n&nbsp;3D<\/a> para conocer m\u00e1s de este incre\u00edble material.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cfcc56 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cfcc56\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a801b07\" data-id=\"a801b07\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6079ea5 elementor-widget elementor-widget-heading\" data-id=\"6079ea5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Par\u00e1metros de Impresi\u00f3n:<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-39c2946\" data-id=\"39c2946\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2639617 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2639617\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Temperatura boquilla: 220 - 250 \u00baC<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Temperatura plataforma: 60 - 90 \u00baC<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Distancia de retroacci\u00f3n: 3 - 4 mm<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Altura de capa: 0.2 mm<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6495e5b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6495e5b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-873ae7c\" data-id=\"873ae7c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cce29de elementor-widget elementor-widget-image\" data-id=\"cce29de\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1587\" height=\"1871\" src=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-TPU.png\" class=\"attachment-large size-large wp-image-606\" alt=\"Im\u00e1genes de piezas elaboradas con filamento TPU.\" srcset=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-TPU.png 1587w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-TPU-768x905.png 768w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-TPU-1303x1536.png 1303w\" sizes=\"(max-width: 1587px) 100vw, 1587px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Piezas elaboradas con filamento TPU.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b4c978 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9b4c978\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df550ef\" data-id=\"df550ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0cde759 elementor-widget elementor-widget-heading\" data-id=\"0cde759\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">4. Filamento TPU (Poliuretano Termopl\u00e1stico)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1262199 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1262199\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-be7bbd1\" data-id=\"be7bbd1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4da1fdc elementor-widget elementor-widget-text-editor\" data-id=\"4da1fdc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tSe caracteriza por tener una gran flexibilidad y durabilidad en la transformaci\u00f3n. Es decir, soporta grandes fuerzas de compresi\u00f3n y tracci\u00f3n. Debido a sus propiedades de moldearse, extruirse y reutilizarse se lo considera como un material reciclable. Tiene varias ventajas como una alta resistencia al impacto, al desgaste, a la abrasi\u00f3n y a los cortes. Sin embargo, a pesar de tener un amplio rango de trabajo, no soporta altas temperaturas.\n<br>\n<br>\nTiene interesantes aplicaciones como la creaci\u00f3n de suelas el\u00e1sticas, la elaboraci\u00f3n de modelos m\u00e9dicos ortop\u00e9dicos y la fabricaci\u00f3n de protectores en equipos fitness. Se lo utiliza para hacer piezas de uso final como fundas de celulares. La industria aeroespacial usa este material para desarrollar instrumentos o sensores. Tambi\u00e9n ha servido para crear neum\u00e1ticos y amortiguadores en el sector de la automoci\u00f3n.\n<br>\n<br>\nA la hora de imprimir se sugiere fijar el material mediante una fina capa de pegamento en la cama de impresi\u00f3n. La temperatura de extrusi\u00f3n debe alcanzar una temperatura de entre 210 y 235&nbsp;&deg;C. En general, durante el proceso de impresi\u00f3n no presenta problemas de deformaci\u00f3n ni delaminaci\u00f3n. Sin embargo, se recomienda que su forma se oriente cerca de la plataforma de fabricaci\u00f3n. Esto dado que las partes m\u00e1s delgadas y altas tienen dificultada para imprimirse. Mira tambi\u00e9n la <a href=\"https:\/\/www.3dnatives.com\/es\/guia-completa-tpu-040620202\/\" rel=\"noopener\" target=\"_blank\">Gu\u00eda&nbsp;completa: El&nbsp;TPU&nbsp;en&nbsp;la&nbsp;impresi\u00f3n&nbsp;3D<\/a>  para saber m\u00e1s detalles del TPU.\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31c2cb9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31c2cb9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-18e9b09\" data-id=\"18e9b09\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3d6778 elementor-widget elementor-widget-heading\" data-id=\"f3d6778\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Par\u00e1metros de Impresi\u00f3n:<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b59400e\" data-id=\"b59400e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8357a8e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8357a8e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Temperatura boquilla: 210 - 235 \u00baC<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Temperatura plataforma: Ambiente<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Distancia m\u00e1xima de retroacci\u00f3n: 1 mm <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Altura m\u00ednima de capa: 0.2 mm<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c1b972c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c1b972c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ee5520\" data-id=\"7ee5520\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81e55e2 elementor-widget elementor-widget-image\" data-id=\"81e55e2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1587\" height=\"1118\" src=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-ASA.png\" class=\"attachment-large size-large wp-image-610\" alt=\"Im\u00e1genes de piezas elaboradas con filamento ASA\" srcset=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-ASA.png 1587w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-ASA-768x541.png 768w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-ASA-1536x1082.png 1536w\" sizes=\"(max-width: 1587px) 100vw, 1587px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Piezas elaboradas con filamento ASA.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ec88d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ec88d8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa14538\" data-id=\"fa14538\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97967d4 elementor-widget elementor-widget-heading\" data-id=\"97967d4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">5. Filamento ASA (Acrilato de Acrilonitrilo Estireno)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d95ec73 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d95ec73\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-839b11f\" data-id=\"839b11f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-459cfce elementor-widget elementor-widget-text-editor\" data-id=\"459cfce\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tEs un material derivado del petr\u00f3leo resistente al impacto y a su vez mantiene su apariencia. Incluso en condiciones adversas como aires, lluvia, fr\u00edo y calor. Esto es ideal ya que no se deteriora ni decolora por su exposici\u00f3n a los rayos UV. Adem\u00e1s, este material resiste productos qu\u00edmicos, altas temperaturas y al agua.\n<br><br>\nLa alta resistencia del ASA hace que sea popular en productos de uso cotidiano. Por ejemplo, para el recubrimiento de techos, en cajas de conexiones el\u00e9ctricas y elementos estructurales exteriores como tubos y perfiles de construcci\u00f3n. Tambi\u00e9n se lo utiliza para partes externas de los veh\u00edculos y juguetes.\n<br><br>\nEste material requiere una temperatura de extrusi\u00f3n de entre 220 y 245&nbsp;&deg;C. La temperatura de la cama para la impresi\u00f3n se mantiene entre 90 y 110&nbsp;&deg;C. Se recomienda evitar los efectos del sobrecalentamiento usando un ventilador a velocidades lentas. Tambi\u00e9n, a causa de la producci\u00f3n de humos potencialmente peligrosos hay que asegurar que el espacio de la impresi\u00f3n este ventilado y usar protecci\u00f3n personal adecuada. Aprende m\u00e1s sobre ASA en <a href=\"https:\/\/impresiona3d.net\/guia-completa-filamento-asa-todo-lo-que-necesitas\/\" target=\"_blank\" rel=\"noopener\">Gu\u00eda&nbsp;Completa&nbsp;Filamento&nbsp;ASA: Todo&nbsp;Lo&nbsp;Que&nbsp;Necesitas<\/a>.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e7a60e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e7a60e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9e8d197\" data-id=\"9e8d197\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8bd08a1 elementor-widget elementor-widget-heading\" data-id=\"8bd08a1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Par\u00e1metros de Impresi\u00f3n:<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7b2074a\" data-id=\"7b2074a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1669319 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1669319\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Temperatura boquilla: 220 - 245 \u00baC<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Temperatura plataforma: 90 - 110 \u00baC<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Distancia de retroacci\u00f3n: 3 - 6 mm<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Altura m\u00e1xima de capa: 0.15 mm<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa629ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa629ea\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e63b53d\" data-id=\"e63b53d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-524761d elementor-widget elementor-widget-image\" data-id=\"524761d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1587\" height=\"1874\" src=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-PVA.png\" class=\"attachment-large size-large wp-image-611\" alt=\"Im\u00e1genes de piezas elaboradas con filamento PVA.\" srcset=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-PVA.png 1587w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-PVA-768x907.png 768w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-PVA-1301x1536.png 1301w\" sizes=\"(max-width: 1587px) 100vw, 1587px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Piezas elaboradas con filamento PVA.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ead40ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ead40ff\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d8e2cc\" data-id=\"3d8e2cc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-391b775 elementor-widget elementor-widget-heading\" data-id=\"391b775\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">6. Filamento PVA (Alcohol Polivin\u00edlico)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bfdccd8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bfdccd8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b4d569\" data-id=\"7b4d569\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-275fcc1 elementor-widget elementor-widget-text-editor\" data-id=\"275fcc1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tEste material es conocido principalmente por su capacidad de disolverse en agua. Cuando est\u00e1 seco llega a ser quebradizo y fr\u00e1gil. Sin embargo, puede ser flexible y el\u00e1stico si se expone a humedad del aire o agua. Adem\u00e1s, tambi\u00e9n es formador de capas, adhesivo y biodegradable.\n<br>\n<br>\nLa solubilidad del PVA lo hace muy \u00fatil como aditivo en la creaci\u00f3n de geometr\u00edas complejas, cavidades, internas, modelos conceptuales y moldes. Por eso es popular en la creaci\u00f3n de modelos decorativos en el mundo del arte. Por otro lado, el PVA ayuda a conseguir una mejor calidad superficial y permite alinear la pieza durante la impresi\u00f3n. Estas caracter\u00edsticas son indispensables para la producci\u00f3n de herramientas o prototipos mediante soportes.\n<br>\n<br>\nSe recomienda combinar el PVA con materiales que tengan un punto de fusi\u00f3n similar. Esto se debe a que la temperatura de degeneraci\u00f3n del PVA es relativamente baja (200&nbsp;&deg;C). Por lo que la temperatura de extrusi\u00f3n ideal esta entre los 180 y 225&nbsp;&deg;C. La cama de impresi\u00f3n debe mantener una temperatura entre los 60 y 90&nbsp;&deg;C. Lee <a href=\"https:\/\/www.3dnatives.com\/es\/pva-impresion-3d-filamento-soluble-230520222\/#!\" rel=\"noopener\" target=\"_blank\">El&nbsp;PVA&nbsp;en&nbsp;la&nbsp;impresi\u00f3n&nbsp;3D, \u00a1todo&nbsp;lo&nbsp;que&nbsp;debes&nbsp;saber sobre&nbsp;este&nbsp;filamento&nbsp;soluble!<\/a> para enterarte de m\u00e1s consejos de c\u00f3mo utilizar este filamento.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c82fff7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c82fff7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0285712\" data-id=\"0285712\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a896e79 elementor-widget elementor-widget-heading\" data-id=\"a896e79\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Par\u00e1metros de Impresi\u00f3n:<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e6dd1c2\" data-id=\"e6dd1c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6a452a elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b6a452a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Temperatura boquilla: 180 - 225 \u00baC<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Temperatura plataforma: 60 - 90 \u00baC<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Distancia de retroacci\u00f3n: 5 mm<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Altura de capa: 0.2 - 0.4 mm<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-63b9dac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63b9dac\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72ee69c\" data-id=\"72ee69c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-567a146 elementor-widget elementor-widget-image\" data-id=\"567a146\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1199\" height=\"1376\" src=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-PVB.png\" class=\"attachment-large size-large wp-image-615\" alt=\"Im\u00e1genes de piezas elaboradas con filamento PVB\" srcset=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-PVB.png 1199w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-PVB-768x881.png 768w\" sizes=\"(max-width: 1199px) 100vw, 1199px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Piezas elaboradas con  filamento PVB.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d424eb4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d424eb4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fddd448\" data-id=\"fddd448\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3486cad elementor-widget elementor-widget-heading\" data-id=\"3486cad\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">7. Filamento PVB (Butirato de Polivinilo)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1713751 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1713751\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0910226\" data-id=\"0910226\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0550f0f elementor-widget elementor-widget-text-editor\" data-id=\"0550f0f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tEl PVB cuenta con una solubilidad en alcohol isoprop\u00edlico. Esta propiedad es \u00fatil para alisar las piezas. As\u00ed, en conjunto con su translucidez se consigue un acabado similar al vidrio. Tambi\u00e9n es muy pr\u00e1ctico para imprimir piezas de gran tama\u00f1o porque tiene una baja deformaci\u00f3n. Sin embargo, se debe tener en cuenta que no tiene muy buena resistencia a altas temperaturas.\n<br><br>\nEn general, tiene aplicaciones para fines visuales. Se usa para hacer jarrones, joyas, pantallas de l\u00e1mparas, etc. Adem\u00e1s, es com\u00fan usarlo en el teatro y cine para complementar disfraces o el conjunto de objetos necesarios para las escenas.\n<br><br>\nLa temperatura de extrusi\u00f3n ideal del PVB ronda los 215&nbsp;&deg;C con una tolerancia de 10&nbsp;&deg;C. La cama de impresi\u00f3n se recomienda tener a 75&nbsp;&deg;C. Se considera que el PVB es similar para imprimir al PLA. Sin embargo, sus propiedades mec\u00e1nicas son mejores, parecidas al PETG. Revisa m\u00e1s informaci\u00f3n del <a href=\"https:\/\/help.prusa3d.com\/es\/article\/pvb_196708\" rel=\"noopener\" target=\"_blank\">PVB<\/a> en prusa3d.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-644a681 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"644a681\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6446972\" data-id=\"6446972\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8dab203 elementor-widget elementor-widget-heading\" data-id=\"8dab203\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Par\u00e1metros de Impresi\u00f3n:<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e9f673b\" data-id=\"e9f673b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40f3c14 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"40f3c14\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Temperatura boquilla: 205 - 225 \u00baC<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Temperatura plataforma: 75 \u00baC<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Distancia de retroacci\u00f3n: 1 - 2 mm<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Altura de capa: 0.12 - 0.16 mm<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-646149a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"646149a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48d3e66\" data-id=\"48d3e66\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3291536 elementor-widget elementor-widget-image\" data-id=\"3291536\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1587\" height=\"1837\" src=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-PC.png\" class=\"attachment-large size-large wp-image-619\" alt=\"Im\u00e1genes de piezas de policarbonato.\" srcset=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-PC.png 1587w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-PC-768x889.png 768w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-PC-1327x1536.png 1327w\" sizes=\"(max-width: 1587px) 100vw, 1587px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Piezas elaboradas con policarbonato.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a39bc48 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a39bc48\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b4711a\" data-id=\"7b4711a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1195c0 elementor-widget elementor-widget-heading\" data-id=\"f1195c0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">8. Filamento PC (Policarbonato)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb3e962 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb3e962\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e5f132\" data-id=\"7e5f132\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac3f0b3 elementor-widget elementor-widget-text-editor\" data-id=\"ac3f0b3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tEl policarbonato destaca por su resistencia a los impactos, los ara\u00f1azos y el calor. Es un material transparente y ligero por lo que tiene aplicaciones \u00f3pticas. Sin embargo, no resiste el contacto con productos qu\u00edmicos ni tampoco la luz ultravioleta. \n<br><br>\nEs un material que no puede exponerse al sol de forma prolongada. Pero su resistencia al calor y a la tracci\u00f3n lo hace ideal para crear piezas mec\u00e1nicas. As\u00ed se utiliza en moldes para termoformado, bisagras, prototipos funcionales y cojinetes de poleas. \n<br><br>\nNo es un pol\u00edmero f\u00e1cil de imprimir. Esto debido a las altas temperaturas de impresi\u00f3n necesarias. Que pueden variar entre los 260 y 320&nbsp;&deg;C para la temperatura de extrusi\u00f3n y 110&nbsp;&deg;C para la cama de impresi\u00f3n. Es necesario tambi\u00e9n usar una soluci\u00f3n adhesiva en la bandeja y un recinto cerrado durante la impresi\u00f3n. Conoce  m\u00e1s sobre el policarbonato en <a href=\"https:\/\/www.3dnatives.com\/es\/el-plastico-de-policarbonato-en-la-impresion-3d-110220202\/\" rel=\"noopener\" target=\"_blank\">Gu\u00eda&nbsp;completa: El&nbsp;pl\u00e1stico&nbsp;de&nbsp;policarbonato en&nbsp;la&nbsp;impresi\u00f3n&nbsp;3D<\/a>.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e292553 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e292553\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9a933f5\" data-id=\"9a933f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-808b61f elementor-widget elementor-widget-heading\" data-id=\"808b61f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Par\u00e1metros de Impresi\u00f3n:<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8baa1ee\" data-id=\"8baa1ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-167ef69 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"167ef69\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Temperatura boquilla: 260 - 320 \u00baC<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Temperatura plataforma: 110 \u00baC<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Distancia m\u00e1xima de retroacci\u00f3n: 10 mm<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Altura de capa: 0.1 - 0.3 mm<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-615fb01 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"615fb01\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44a63c7\" data-id=\"44a63c7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7a12d2 elementor-widget elementor-widget-image\" data-id=\"b7a12d2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1587\" height=\"2245\" src=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-fibra-carbono.png\" class=\"attachment-large size-large wp-image-620\" alt=\"Pieza elaborada con filamento reforzado con fibra de carbono\" srcset=\"https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-fibra-carbono.png 1587w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-fibra-carbono-768x1086.png 768w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-fibra-carbono-1086x1536.png 1086w, https:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/AplicacionesFilamentos-fibra-carbono-1448x2048.png 1448w\" sizes=\"(max-width: 1587px) 100vw, 1587px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Pieza elaborada con filamento reforzado con  fibra de carbono.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2325e28 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2325e28\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fe71b73\" data-id=\"fe71b73\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db5e99c elementor-widget elementor-widget-heading\" data-id=\"db5e99c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">9. Filamento reforzado con fibra de carbono<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c5c64bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c5c64bd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8735ac8\" data-id=\"8735ac8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebae0d1 elementor-widget elementor-widget-text-editor\" data-id=\"ebae0d1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tLa fibra de carbono es un material formado por una cadena larga de \u00e1tomos de carbono interconectados. Son sumamente peque\u00f1as, siendo su di\u00e1metro entre 5 y 10 micr\u00f3metros. En la pr\u00e1ctica, se combina con otros materiales (filamentos como PLA, PETG, nylon, ABS, policarbonato, etc.) formando composites. Es decir, materiales reforzados con fibra de carbono.\n<br><br>\nEl resultado son piezas sumamente fuertes, ligeras y con mayor rigidez. Estos superan a la mayor\u00eda de filamentos en cuesti\u00f3n de tenacidad y resistencia a la temperatura. Tiene aplicaciones en sectores como el aeroespacial, automotriz, militar o ingenier\u00eda civil. Esto debido a que permite crear piezas personalizadas con mejor rendimiento.\n<br>\n<br>\nLos par\u00e1metros para el proceso de impresi\u00f3n dependen del material base reforzado con la fibra de carbono. Sin embargo, se recomienda usar una boquilla de acero endurecido para evitar obstrucciones por las fibras agregadas. Adem\u00e1s, se puede conseguir un resultado m\u00e1s fuerte usando una t\u00e9cnica llamada refuerzo continuo de fibra de carbono. Aprende m\u00e1s sobre la fibra de carbono y sus beneficios en <a href=\"https:\/\/www.3dnatives.com\/es\/fibra-de-carbono-impresion-3d-050520202\/#!\" target=\"_blank\" rel=\"noopener\">Todo&nbsp;lo&nbsp;que\u00a0necesitas&nbsp;saber&nbsp;sobre la&nbsp;fibra&nbsp;de&nbsp;carbono&nbsp;en&nbsp;impresi\u00f3n&nbsp;3D<\/a>.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-affa040 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"affa040\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cb2afb6\" data-id=\"cb2afb6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-884b8d9 elementor-widget elementor-widget-heading\" data-id=\"884b8d9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Se resalta que filamentos populares como el PLA y ABS son a su vez, amigables con el medio ambiente. Tambi\u00e9n se recuerda mantener precauci\u00f3n con filamentos como el ABS y el ASA que emiten part\u00edculas nocivas.<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-652e5cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"652e5cc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f04bf9e\" data-id=\"f04bf9e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5011e9b elementor-widget elementor-widget-text-editor\" data-id=\"5011e9b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Por \u00faltimo, recuerda que los par\u00e1metros de impresi\u00f3n est\u00e1n recomendados para extrusores de accionamiento directo por lo que debes ajustar los par\u00e1metros asegurando que consigas el mejor resultado para tu caso particular. Esperando que te haya sido \u00fatil nuestro art\u00edculo sobre filamentos PLA, ABS, ASA, policarbonato y m\u00e1s en la impresi\u00f3n 3D te invitamos a leer el resto de nuestros art\u00edculos! Si te interesa saber m\u00e1s tips para mejorar la calidad de tus impresiones te sugerimos leer nuestro post <a href=\"https:\/\/sais3d.com\/index.php\/2023\/09\/19\/falta-de-adherencia-a-la-cama-de-impresion\/\" target=\"_blank\" rel=\"noopener\">Falta de adherencia a la cama de impresi\u00f3n<\/a>. Tambi\u00e9n, revisa nuestra p\u00e1gina web <a href=\"https:\/\/skp3d.com\/product-category\/filament\/\" target=\"_blank\" rel=\"noopener\">SKP3D<\/a> y pregunta por nuestro variado conjunto de filamentos en PLA, ABS, ASA, PETG.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Las impresoras 3D permiten dise\u00f1ar y crear piezas \u00fanicas e innovadoras. Estas son muy \u00fatiles en \u00e1reas t\u00e9cnicas como son&hellip;<\/p>\n","protected":false},"author":1,"featured_media":663,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Filamentos PLA, ABS, ASA y m\u00e1s en impresi\u00f3n 3D - SAIS3D<\/title>\n<meta name=\"description\" content=\"Descubre tipos de filamentos populares como PLA, ABS, ASA en impresi\u00f3n 3D. Aprende sobre sus caracter\u00edsticas y aplicaciones en la industria.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Filamentos PLA, ABS, ASA y m\u00e1s en impresi\u00f3n 3D - SAIS3D\" \/>\n<meta property=\"og:description\" content=\"Descubre tipos de filamentos populares como PLA, ABS, ASA en impresi\u00f3n 3D. Aprende sobre sus caracter\u00edsticas y aplicaciones en la industria.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/\" \/>\n<meta property=\"og:site_name\" content=\"SAIS3D\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-12T23:02:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-15T05:33:01+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/Aplicaciones-Filamentos-portada-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1766\" \/>\n\t<meta property=\"og:image:height\" content=\"1182\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"sais3d.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"sais3d.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/\"},\"author\":{\"name\":\"sais3d.com\",\"@id\":\"https:\/\/sais3d.com\/#\/schema\/person\/ee39e607c227f04852e00e077217e5e1\"},\"headline\":\"Filamentos PLA, ABS, ASA y m\u00e1s en impresi\u00f3n 3D\",\"datePublished\":\"2024-07-12T23:02:36+00:00\",\"dateModified\":\"2024-07-15T05:33:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/\"},\"wordCount\":2785,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sais3d.com\/#organization\"},\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/\",\"url\":\"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/\",\"name\":\"Filamentos PLA, ABS, ASA y m\u00e1s en impresi\u00f3n 3D - SAIS3D\",\"isPartOf\":{\"@id\":\"https:\/\/sais3d.com\/#website\"},\"datePublished\":\"2024-07-12T23:02:36+00:00\",\"dateModified\":\"2024-07-15T05:33:01+00:00\",\"description\":\"Descubre tipos de filamentos populares como PLA, ABS, ASA en impresi\u00f3n 3D. Aprende sobre sus caracter\u00edsticas y aplicaciones en la industria.\",\"breadcrumb\":{\"@id\":\"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sais3d.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Filamentos PLA, ABS, ASA y m\u00e1s en impresi\u00f3n 3D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sais3d.com\/#website\",\"url\":\"https:\/\/sais3d.com\/\",\"name\":\"SAIS3D\",\"description\":\"Tu blog de impresi\u00f3n 3D\",\"publisher\":{\"@id\":\"https:\/\/sais3d.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sais3d.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sais3d.com\/#organization\",\"name\":\"SAIS3D\",\"url\":\"https:\/\/sais3d.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sais3d.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sais3d.com\/wp-content\/uploads\/2023\/09\/cropped-Diseno-sin-titulo-4-1.png\",\"contentUrl\":\"https:\/\/sais3d.com\/wp-content\/uploads\/2023\/09\/cropped-Diseno-sin-titulo-4-1.png\",\"width\":250,\"height\":123,\"caption\":\"SAIS3D\"},\"image\":{\"@id\":\"https:\/\/sais3d.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/sais3d.com\/#\/schema\/person\/ee39e607c227f04852e00e077217e5e1\",\"name\":\"sais3d.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sais3d.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1a69b36e0888b46d18adb45de657de15?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1a69b36e0888b46d18adb45de657de15?s=96&d=mm&r=g\",\"caption\":\"sais3d.com\"},\"sameAs\":[\"http:\/\/sais3d.com\"],\"url\":\"https:\/\/sais3d.com\/index.php\/author\/sais3d-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Filamentos PLA, ABS, ASA y m\u00e1s en impresi\u00f3n 3D - SAIS3D","description":"Descubre tipos de filamentos populares como PLA, ABS, ASA en impresi\u00f3n 3D. Aprende sobre sus caracter\u00edsticas y aplicaciones en la industria.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/","og_locale":"en_US","og_type":"article","og_title":"Filamentos PLA, ABS, ASA y m\u00e1s en impresi\u00f3n 3D - SAIS3D","og_description":"Descubre tipos de filamentos populares como PLA, ABS, ASA en impresi\u00f3n 3D. Aprende sobre sus caracter\u00edsticas y aplicaciones en la industria.","og_url":"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/","og_site_name":"SAIS3D","article_published_time":"2024-07-12T23:02:36+00:00","article_modified_time":"2024-07-15T05:33:01+00:00","og_image":[{"width":1766,"height":1182,"url":"http:\/\/sais3d.com\/wp-content\/uploads\/2024\/07\/Aplicaciones-Filamentos-portada-1.png","type":"image\/png"}],"author":"sais3d.com","twitter_card":"summary_large_image","twitter_misc":{"Written by":"sais3d.com","Est. reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/#article","isPartOf":{"@id":"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/"},"author":{"name":"sais3d.com","@id":"https:\/\/sais3d.com\/#\/schema\/person\/ee39e607c227f04852e00e077217e5e1"},"headline":"Filamentos PLA, ABS, ASA y m\u00e1s en impresi\u00f3n 3D","datePublished":"2024-07-12T23:02:36+00:00","dateModified":"2024-07-15T05:33:01+00:00","mainEntityOfPage":{"@id":"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/"},"wordCount":2785,"commentCount":0,"publisher":{"@id":"https:\/\/sais3d.com\/#organization"},"articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/","url":"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/","name":"Filamentos PLA, ABS, ASA y m\u00e1s en impresi\u00f3n 3D - SAIS3D","isPartOf":{"@id":"https:\/\/sais3d.com\/#website"},"datePublished":"2024-07-12T23:02:36+00:00","dateModified":"2024-07-15T05:33:01+00:00","description":"Descubre tipos de filamentos populares como PLA, ABS, ASA en impresi\u00f3n 3D. Aprende sobre sus caracter\u00edsticas y aplicaciones en la industria.","breadcrumb":{"@id":"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sais3d.com\/index.php\/2024\/07\/12\/filamentos-pla-abs-asa-y-mas-en-impresion-3d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sais3d.com\/"},{"@type":"ListItem","position":2,"name":"Filamentos PLA, ABS, ASA y m\u00e1s en impresi\u00f3n 3D"}]},{"@type":"WebSite","@id":"https:\/\/sais3d.com\/#website","url":"https:\/\/sais3d.com\/","name":"SAIS3D","description":"Tu blog de impresi\u00f3n 3D","publisher":{"@id":"https:\/\/sais3d.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sais3d.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sais3d.com\/#organization","name":"SAIS3D","url":"https:\/\/sais3d.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sais3d.com\/#\/schema\/logo\/image\/","url":"https:\/\/sais3d.com\/wp-content\/uploads\/2023\/09\/cropped-Diseno-sin-titulo-4-1.png","contentUrl":"https:\/\/sais3d.com\/wp-content\/uploads\/2023\/09\/cropped-Diseno-sin-titulo-4-1.png","width":250,"height":123,"caption":"SAIS3D"},"image":{"@id":"https:\/\/sais3d.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sais3d.com\/#\/schema\/person\/ee39e607c227f04852e00e077217e5e1","name":"sais3d.com","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sais3d.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1a69b36e0888b46d18adb45de657de15?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1a69b36e0888b46d18adb45de657de15?s=96&d=mm&r=g","caption":"sais3d.com"},"sameAs":["http:\/\/sais3d.com"],"url":"https:\/\/sais3d.com\/index.php\/author\/sais3d-com\/"}]}},"_links":{"self":[{"href":"https:\/\/sais3d.com\/index.php\/wp-json\/wp\/v2\/posts\/351"}],"collection":[{"href":"https:\/\/sais3d.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sais3d.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sais3d.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sais3d.com\/index.php\/wp-json\/wp\/v2\/comments?post=351"}],"version-history":[{"count":0,"href":"https:\/\/sais3d.com\/index.php\/wp-json\/wp\/v2\/posts\/351\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sais3d.com\/index.php\/wp-json\/wp\/v2\/media\/663"}],"wp:attachment":[{"href":"https:\/\/sais3d.com\/index.php\/wp-json\/wp\/v2\/media?parent=351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sais3d.com\/index.php\/wp-json\/wp\/v2\/categories?post=351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sais3d.com\/index.php\/wp-json\/wp\/v2\/tags?post=351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}